{"id":2083,"date":"2026-05-07T14:55:46","date_gmt":"2026-05-07T17:55:46","guid":{"rendered":"https:\/\/camarasalto.sp.gov.br\/tvweb\/?post_type=videos&#038;p=2083"},"modified":"2026-05-07T14:55:48","modified_gmt":"2026-05-07T17:55:48","slug":"3a-reuniao-comissao-de-organizacao-07-05-2026","status":"publish","type":"videos","link":"https:\/\/camarasalto.sp.gov.br\/tvweb\/videos\/3a-reuniao-comissao-de-organizacao-07-05-2026\/","title":{"rendered":"3\u00aa Reuni\u00e3o \u2013 Comiss\u00e3o de Organiza\u00e7\u00e3o \u2013 07-05-2026"},"content":{"rendered":"","protected":false},"featured_media":0,"template":"","meta":{"_acf_changed":true,"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":""},"class_list":["post-2083","videos","type-videos","status-publish","hentry"],"acf":{"video_url":"https:\/\/camarasalto.sp.gov.br\/player\/comissoes\/2026\/corg\/03-comissao-organizacao-07-05-2026.mp4","video_categoria":"10","data_video":"20260507","anexar_pauta":{"texto_botao_arquivo_pauta":"Pauta","arquivo_pauta":""},"anexar_ata":{"texto_botao_arquivo_ata":"Ata","arquivo_ata":""}},"views":23,"_links":{"self":[{"href":"https:\/\/camarasalto.sp.gov.br\/tvweb\/wp-json\/wp\/v2\/videos\/2083","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/camarasalto.sp.gov.br\/tvweb\/wp-json\/wp\/v2\/videos"}],"about":[{"href":"https:\/\/camarasalto.sp.gov.br\/tvweb\/wp-json\/wp\/v2\/types\/videos"}],"wp:attachment":[{"href":"https:\/\/camarasalto.sp.gov.br\/tvweb\/wp-json\/wp\/v2\/media?parent=2083"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}